{"id":1253,"date":"2022-10-10T12:04:32","date_gmt":"2022-10-10T12:04:32","guid":{"rendered":"https:\/\/vergelijkbookmakers.nl\/?p=1253"},"modified":"2022-10-10T12:04:32","modified_gmt":"2022-10-10T12:04:32","slug":"niemand-verwacht-iets-van-de-ploeg-van-schreuder","status":"publish","type":"post","link":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/","title":{"rendered":"&#8216;Niemand verwacht iets van de ploeg van Schreuder&#8217;"},"content":{"rendered":"<h4>Aanstaande woensdag gaat Ajax in de Champions League op bezoek bij Napoli. En voormalig topvoetballer Willem van Hanegem verwacht weinig van dit treffen. Hij ziet dat de Amsterdammers in een dip zitten en is lovend over de Italiaanse club.<\/h4>\n<p>Van Hanegem stelt dat Ajax afgelopen zaterdag goed is weggekomen tegen FC Volendam (2-4). &#8216;De uitwedstrijd tegen Napoli deze week is dan wel weer een heel ander verhaal voor Ajax, want na die enorme tik in Amsterdam verwacht eigenlijk niemand iets van de ploeg van Schreuder&#8217;, schrijft hij in zijn column voor het Algemeen Dagblad. &#8216;Misschien zelfs Napoli niet, want die waren zoveel beter in Amsterdam.&#8217;<\/p>\n<p>Dat Napoli Ajax in de Johan Cruijff Arena overklaste, kwam volgens Van Hanegem niet uit de lucht vallen. &#8216;En o ja, de mensen die dinsdagavond riepen dat ze verrast waren dat Napoli zo goed was, hebben even een tijdje onder een steen geleefd. Dat was alle voetballiefhebbers toch al opgevallen, dat ze daar heerlijk spelen? Napoli is zo goed, denk ik, omdat ze maar blijven doen waar ze goed in zijn. Dus gewoon gas blijven geven, ook al staat het 1-6.&#8217;<\/p>\n<p>Volgens de ras-Feyenoorder is dat in strijd met de denkwijze van veel hedendaagse trainers. &#8216;Ik zie en hoor hier veel te vaak dat gezeur dat ze moeten sparen&#8217;, schrijft hij. &#8216;Overal maar zo min mogelijk energie verspillen. Maar dat werkt niet. Je moet in de hoogste versnelling leren spelen, het gevoel krijgen dat je niet kapot kunt. Dat lukt je nooit als je voortdurend maar de voet van het gas haalt.&#8217;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aanstaande woensdag gaat Ajax in de Champions League op bezoek bij Napoli. En voormalig topvoetballer Willem van Hanegem verwacht weinig van dit treffen. Hij ziet dat de Amsterdammers in een dip zitten en is lovend over de Italiaanse club. Van Hanegem stelt dat Ajax afgelopen zaterdag goed is weggekomen tegen FC Volendam (2-4). &#8216;De uitwedstrijd [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voetbalnieuws"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;Niemand verwacht iets van de ploeg van Schreuder&#039; - Bookmakers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Niemand verwacht iets van de ploeg van Schreuder&#039; - Bookmakers\" \/>\n<meta property=\"og:description\" content=\"Aanstaande woensdag gaat Ajax in de Champions League op bezoek bij Napoli. En voormalig topvoetballer Willem van Hanegem verwacht weinig van dit treffen. Hij ziet dat de Amsterdammers in een dip zitten en is lovend over de Italiaanse club. Van Hanegem stelt dat Ajax afgelopen zaterdag goed is weggekomen tegen FC Volendam (2-4). &#8216;De uitwedstrijd [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/\" \/>\n<meta property=\"og:site_name\" content=\"Bookmakers\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T12:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"spenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"spenz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/\"},\"author\":{\"name\":\"spenz\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#\\\/schema\\\/person\\\/d0b08bbe6ddd05b12cab6fcddc4abc84\"},\"headline\":\"&#8216;Niemand verwacht iets van de ploeg van Schreuder&#8217;\",\"datePublished\":\"2022-10-10T12:04:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/\"},\"wordCount\":265,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-8.jpg\",\"articleSection\":[\"Voetbalnieuws\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/\",\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/\",\"name\":\"'Niemand verwacht iets van de ploeg van Schreuder' - Bookmakers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-8.jpg\",\"datePublished\":\"2022-10-10T12:04:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#\\\/schema\\\/person\\\/d0b08bbe6ddd05b12cab6fcddc4abc84\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-8.jpg\",\"contentUrl\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-8.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/10\\\/10\\\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Niemand verwacht iets van de ploeg van Schreuder&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#website\",\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/\",\"name\":\"Bookmakers\",\"description\":\"Voetbalweddenschappen, Online Gokken en Voetbalnieuws\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#\\\/schema\\\/person\\\/d0b08bbe6ddd05b12cab6fcddc4abc84\",\"name\":\"spenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"caption\":\"spenz\"},\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/author\\\/spenz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Niemand verwacht iets van de ploeg van Schreuder' - Bookmakers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/","og_locale":"nl_NL","og_type":"article","og_title":"'Niemand verwacht iets van de ploeg van Schreuder' - Bookmakers","og_description":"Aanstaande woensdag gaat Ajax in de Champions League op bezoek bij Napoli. En voormalig topvoetballer Willem van Hanegem verwacht weinig van dit treffen. Hij ziet dat de Amsterdammers in een dip zitten en is lovend over de Italiaanse club. Van Hanegem stelt dat Ajax afgelopen zaterdag goed is weggekomen tegen FC Volendam (2-4). &#8216;De uitwedstrijd [&hellip;]","og_url":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/","og_site_name":"Bookmakers","article_published_time":"2022-10-10T12:04:32+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-8.jpg","type":"image\/jpeg"}],"author":"spenz","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"spenz"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#article","isPartOf":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/"},"author":{"name":"spenz","@id":"https:\/\/vergelijkbookmakers.nl\/#\/schema\/person\/d0b08bbe6ddd05b12cab6fcddc4abc84"},"headline":"&#8216;Niemand verwacht iets van de ploeg van Schreuder&#8217;","datePublished":"2022-10-10T12:04:32+00:00","mainEntityOfPage":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/"},"wordCount":265,"commentCount":0,"image":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#primaryimage"},"thumbnailUrl":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-8.jpg","articleSection":["Voetbalnieuws"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/","url":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/","name":"'Niemand verwacht iets van de ploeg van Schreuder' - Bookmakers","isPartOf":{"@id":"https:\/\/vergelijkbookmakers.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#primaryimage"},"image":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#primaryimage"},"thumbnailUrl":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-8.jpg","datePublished":"2022-10-10T12:04:32+00:00","author":{"@id":"https:\/\/vergelijkbookmakers.nl\/#\/schema\/person\/d0b08bbe6ddd05b12cab6fcddc4abc84"},"breadcrumb":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#primaryimage","url":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-8.jpg","contentUrl":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-8.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/10\/10\/niemand-verwacht-iets-van-de-ploeg-van-schreuder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vergelijkbookmakers.nl\/"},{"@type":"ListItem","position":2,"name":"&#8216;Niemand verwacht iets van de ploeg van Schreuder&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/vergelijkbookmakers.nl\/#website","url":"https:\/\/vergelijkbookmakers.nl\/","name":"Bookmakers","description":"Voetbalweddenschappen, Online Gokken en Voetbalnieuws","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vergelijkbookmakers.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/vergelijkbookmakers.nl\/#\/schema\/person\/d0b08bbe6ddd05b12cab6fcddc4abc84","name":"spenz","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","caption":"spenz"},"url":"https:\/\/vergelijkbookmakers.nl\/index.php\/author\/spenz\/"}]}},"_links":{"self":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/posts\/1253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":-4,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/posts\/1253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/media\/779"}],"wp:attachment":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/media?parent=1253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/categories?post=1253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/tags?post=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}