{"id":1425,"date":"2022-12-04T08:31:53","date_gmt":"2022-12-04T08:31:53","guid":{"rendered":"https:\/\/vergelijkbookmakers.nl\/?p=1425"},"modified":"2022-12-04T08:31:53","modified_gmt":"2022-12-04T08:31:53","slug":"louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video","status":"publish","type":"post","link":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/","title":{"rendered":"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO)"},"content":{"rendered":"<h4>Denzel Dumfries was gisteren de grote man bij Oranje in het met 3-1 gewonnen duel tegen de VS. Met een goal en maar liefst twee assists was hij bij iedere treffer betrokken. Bondscoach Louis van Gaal is in zijn nopjes met de vleugelverdediger. En daarom gaf hij hem op de persconferentie na de wedstrijd een dikke zoen. Kijk hieronder naar de beelden&#8230;..<\/h4>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"nl\" dir=\"ltr\">Louis van Gaal geeft Denzel Dumfries een dikke zoen tijdens de persconferentie! \ud83d\ude19<a href=\"https:\/\/twitter.com\/hashtag\/deoranjewinter?src=hash&amp;ref_src=twsrc%5Etfw\">#deoranjewinter<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/vandaaginside?src=hash&amp;ref_src=twsrc%5Etfw\">#vandaaginside<\/a> <a href=\"https:\/\/t.co\/xYmrPuWk8K\">pic.twitter.com\/xYmrPuWk8K<\/a><\/p>\n<p>&mdash; Vandaag Inside (@vandaaginside) <a href=\"https:\/\/twitter.com\/vandaaginside\/status\/1599114095466250241?ref_src=twsrc%5Etfw\">December 3, 2022<\/a><\/p><\/blockquote>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Denzel Dumfries was gisteren de grote man bij Oranje in het met 3-1 gewonnen duel tegen de VS. Met een goal en maar liefst twee assists was hij bij iedere treffer betrokken. Bondscoach Louis van Gaal is in zijn nopjes met de vleugelverdediger. En daarom gaf hij hem op de persconferentie na de wedstrijd een [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voetbalnieuws"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO) - Bookmakers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO) - Bookmakers\" \/>\n<meta property=\"og:description\" content=\"Denzel Dumfries was gisteren de grote man bij Oranje in het met 3-1 gewonnen duel tegen de VS. Met een goal en maar liefst twee assists was hij bij iedere treffer betrokken. Bondscoach Louis van Gaal is in zijn nopjes met de vleugelverdediger. En daarom gaf hij hem op de persconferentie na de wedstrijd een [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Bookmakers\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-04T08:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"spenz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"spenz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/\"},\"author\":{\"name\":\"spenz\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#\\\/schema\\\/person\\\/d0b08bbe6ddd05b12cab6fcddc4abc84\"},\"headline\":\"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO)\",\"datePublished\":\"2022-12-04T08:31:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/\"},\"wordCount\":94,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-10.jpg\",\"articleSection\":[\"Voetbalnieuws\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/\",\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/\",\"name\":\"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO) - Bookmakers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-10.jpg\",\"datePublished\":\"2022-12-04T08:31:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#\\\/schema\\\/person\\\/d0b08bbe6ddd05b12cab6fcddc4abc84\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-10.jpg\",\"contentUrl\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/voetbal-10.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/2022\\\/12\\\/04\\\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#website\",\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/\",\"name\":\"Bookmakers\",\"description\":\"Voetbalweddenschappen, Online Gokken en Voetbalnieuws\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/#\\\/schema\\\/person\\\/d0b08bbe6ddd05b12cab6fcddc4abc84\",\"name\":\"spenz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g\",\"caption\":\"spenz\"},\"url\":\"https:\\\/\\\/vergelijkbookmakers.nl\\\/index.php\\\/author\\\/spenz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO) - Bookmakers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/","og_locale":"nl_NL","og_type":"article","og_title":"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO) - Bookmakers","og_description":"Denzel Dumfries was gisteren de grote man bij Oranje in het met 3-1 gewonnen duel tegen de VS. Met een goal en maar liefst twee assists was hij bij iedere treffer betrokken. Bondscoach Louis van Gaal is in zijn nopjes met de vleugelverdediger. En daarom gaf hij hem op de persconferentie na de wedstrijd een [&hellip;]","og_url":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/","og_site_name":"Bookmakers","article_published_time":"2022-12-04T08:31:53+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-10.jpg","type":"image\/jpeg"}],"author":"spenz","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"spenz"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#article","isPartOf":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/"},"author":{"name":"spenz","@id":"https:\/\/vergelijkbookmakers.nl\/#\/schema\/person\/d0b08bbe6ddd05b12cab6fcddc4abc84"},"headline":"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO)","datePublished":"2022-12-04T08:31:53+00:00","mainEntityOfPage":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/"},"wordCount":94,"commentCount":0,"image":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#primaryimage"},"thumbnailUrl":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-10.jpg","articleSection":["Voetbalnieuws"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/","url":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/","name":"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO) - Bookmakers","isPartOf":{"@id":"https:\/\/vergelijkbookmakers.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#primaryimage"},"image":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#primaryimage"},"thumbnailUrl":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-10.jpg","datePublished":"2022-12-04T08:31:53+00:00","author":{"@id":"https:\/\/vergelijkbookmakers.nl\/#\/schema\/person\/d0b08bbe6ddd05b12cab6fcddc4abc84"},"breadcrumb":{"@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#primaryimage","url":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-10.jpg","contentUrl":"https:\/\/vergelijkbookmakers.nl\/wp-content\/uploads\/2022\/04\/voetbal-10.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/vergelijkbookmakers.nl\/index.php\/2022\/12\/04\/louis-van-gaal-zoent-dumfries-tijdens-persconferentie-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vergelijkbookmakers.nl\/"},{"@type":"ListItem","position":2,"name":"Louis van Gaal zoent Dumfries tijdens persconferentie (VIDEO)"}]},{"@type":"WebSite","@id":"https:\/\/vergelijkbookmakers.nl\/#website","url":"https:\/\/vergelijkbookmakers.nl\/","name":"Bookmakers","description":"Voetbalweddenschappen, Online Gokken en Voetbalnieuws","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vergelijkbookmakers.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/vergelijkbookmakers.nl\/#\/schema\/person\/d0b08bbe6ddd05b12cab6fcddc4abc84","name":"spenz","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/457cebb725740d7e0f2f93aa79f0aa7ce5967df259920258723f252437e4c67a?s=96&d=mm&r=g","caption":"spenz"},"url":"https:\/\/vergelijkbookmakers.nl\/index.php\/author\/spenz\/"}]}},"_links":{"self":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/posts\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":-4,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/posts\/1425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/media\/781"}],"wp:attachment":[{"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/media?parent=1425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/categories?post=1425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vergelijkbookmakers.nl\/index.php\/wp-json\/wp\/v2\/tags?post=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}